{"id":167308,"date":"2025-03-24T08:49:22","date_gmt":"2025-03-24T07:49:22","guid":{"rendered":"https:\/\/www.es-karlsruhe.eu\/?p=167308"},"modified":"2025-03-24T08:49:22","modified_gmt":"2025-03-24T07:49:22","slug":"teilnahme-am-kaenguru-wettbewerb-der-mathematik","status":"publish","type":"post","link":"https:\/\/www.es-karlsruhe.eu\/de\/teilnahme-am-kaenguru-wettbewerb-der-mathematik\/","title":{"rendered":"Teilnahme am K\u00e4nguru-Wettbewerb der Mathematik"},"content":{"rendered":"<p>Am Donnerstag, den 20. M\u00e4rz, hatten Sch\u00fclerinnen und Sch\u00fcler der Sekundarschule das Vergn\u00fcgen, am K\u00e4nguru-Wettbewerb teilzunehmen, einem internationalen Mathematikwettbewerb, der das Interesse an diesem Fach bei Sch\u00fclerinnen und Sch\u00fclern f\u00f6rdern soll. Der urspr\u00fcnglich aus Australien stammende Wettbewerb wurde 1995 in Deutschland eingef\u00fchrt und findet jedes Jahr am dritten Donnerstag im M\u00e4rz statt. (<a href=\"https:\/\/www.mathe-kaenguru.de\/\">mathe-kaenguru.de<\/a>)<\/p>\n<p>Beim K\u00e4nguru-Wettbewerb erhalten die Sch\u00fclerinnen und Sch\u00fcler einen Multiple-Choice-Fragebogen mit 24 bis 30 Fragen mit steigendem Schwierigkeitsgrad, je nach Schulstufe der Teilnehmer. Sie haben 75 Minuten Zeit, um diese Aufgaben ohne die Hilfe von Taschenrechnern zu l\u00f6sen, was logisches Denken und Kreativit\u00e4t f\u00f6rdert.<\/p>\n<p>In diesem Jahr nahmen 94 Sch\u00fclerinnen und Sch\u00fcler unserer Oberschule, von der 6. bis zur 12. Klasse, die Herausforderung an und beteiligten sich an dieser herausfordernden Pr\u00fcfung. Wir m\u00f6chten uns herzlich bei der Elternvereinigung bedanken, daf\u00fcr, dass sie die Anmeldegeb\u00fchren f\u00fcr alle Teilnehmer \u00fcbernommen hat, sodass jeder diese bereichernde Erfahrung machen konnte.<\/p>\n<p>Ein besonderer Dank geht an Herrn De Filippi, der die Durchf\u00fchrung des Wettbewerbs in der Schule effizient organisiert und koordiniert hat.<\/p>\n<p>Die Ergebnisse des Wettbewerbs werden in K\u00fcrze bekannt gegeben, und wir werden nat\u00fcrlich die Erfolge unserer Sch\u00fclerinnen und Sch\u00fcler geb\u00fchrend feiern. In der Zwischenzeit gratulieren wir allen Teilnehmern zu ihrem Engagement und ihrer Begeisterung f\u00fcr die Mathematik!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-167304\" src=\"https:\/\/www.es-karlsruhe.eu\/wp-content\/uploads\/2025\/03\/Kangu-200x300.png\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.es-karlsruhe.eu\/wp-content\/uploads\/2025\/03\/Kangu-200x300.png 200w, https:\/\/www.es-karlsruhe.eu\/wp-content\/uploads\/2025\/03\/Kangu-682x1024.png 682w, https:\/\/www.es-karlsruhe.eu\/wp-content\/uploads\/2025\/03\/Kangu-768x1152.png 768w, https:\/\/www.es-karlsruhe.eu\/wp-content\/uploads\/2025\/03\/Kangu-1024x1536.png 1024w, https:\/\/www.es-karlsruhe.eu\/wp-content\/uploads\/2025\/03\/Kangu.png 1333w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Donnerstag, den 20. M\u00e4rz, hatten Sch\u00fclerinnen und Sch\u00fcler der Sekundarschule das Vergn\u00fcgen, am K\u00e4nguru-Wettbewerb teilzunehmen, einem internationalen Mathematikwettbewerb, der das Interesse an diesem Fach bei Sch\u00fclerinnen und Sch\u00fclern f\u00f6rdern<a class=\"excerpt-read-more\" href=\"https:\/\/www.es-karlsruhe.eu\/de\/teilnahme-am-kaenguru-wettbewerb-der-mathematik\/\" title=\"LesenTeilnahme am K\u00e4nguru-Wettbewerb der Mathematik\">\u2026 weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":25,"featured_media":167304,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96],"tags":[],"class_list":["post-167308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-secondary"],"_links":{"self":[{"href":"https:\/\/www.es-karlsruhe.eu\/de\/wp-json\/wp\/v2\/posts\/167308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.es-karlsruhe.eu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.es-karlsruhe.eu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.es-karlsruhe.eu\/de\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.es-karlsruhe.eu\/de\/wp-json\/wp\/v2\/comments?post=167308"}],"version-history":[{"count":1,"href":"https:\/\/www.es-karlsruhe.eu\/de\/wp-json\/wp\/v2\/posts\/167308\/revisions"}],"predecessor-version":[{"id":167309,"href":"https:\/\/www.es-karlsruhe.eu\/de\/wp-json\/wp\/v2\/posts\/167308\/revisions\/167309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.es-karlsruhe.eu\/de\/wp-json\/wp\/v2\/media\/167304"}],"wp:attachment":[{"href":"https:\/\/www.es-karlsruhe.eu\/de\/wp-json\/wp\/v2\/media?parent=167308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.es-karlsruhe.eu\/de\/wp-json\/wp\/v2\/categories?post=167308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.es-karlsruhe.eu\/de\/wp-json\/wp\/v2\/tags?post=167308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}